{"id":448,"count":9,"description":"","link":"https:\/\/klantenservice.corendon.nl\/cbe-fr\/category\/logement\/","name":"Logement","slug":"logement","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Logement Archieven - Corendon Service Client (FR)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fr.corendon.be\/poser\/category\/logement\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Logement Archieven - Corendon Service Client (FR)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/klantenservice.corendon.nl\/cbe-fr\/category\/logement\/\" \/>\n<meta property=\"og:site_name\" content=\"Corendon Service Client (FR)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/klantenservice.corendon.nl\/cbe-fr\/category\/logement\/\",\"url\":\"https:\/\/klantenservice.corendon.nl\/cbe-fr\/category\/logement\/\",\"name\":\"Logement Archieven - Corendon Service Client (FR)\",\"isPartOf\":{\"@id\":\"https:\/\/klantenservice.corendon.nl\/cbe-fr\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/klantenservice.corendon.nl\/cbe-fr\/category\/logement\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/klantenservice.corendon.nl\/cbe-fr\/category\/logement\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/klantenservice.corendon.nl\/cbe-fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Logement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/klantenservice.corendon.nl\/cbe-fr\/#website\",\"url\":\"https:\/\/klantenservice.corendon.nl\/cbe-fr\/\",\"name\":\"Corendon Service Client (FR)\",\"description\":\"Op deze pagina vindt u vrijwel alle antwoorden op vragen met betrekking tot het boeken van uw vakantie\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/klantenservice.corendon.nl\/cbe-fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Logement Archieven - Corendon Service Client (FR)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fr.corendon.be\/poser\/category\/logement\/","og_locale":"fr_FR","og_type":"article","og_title":"Logement Archieven - Corendon Service Client (FR)","og_url":"https:\/\/klantenservice.corendon.nl\/cbe-fr\/category\/logement\/","og_site_name":"Corendon Service Client (FR)","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/klantenservice.corendon.nl\/cbe-fr\/category\/logement\/","url":"https:\/\/klantenservice.corendon.nl\/cbe-fr\/category\/logement\/","name":"Logement Archieven - Corendon Service Client (FR)","isPartOf":{"@id":"https:\/\/klantenservice.corendon.nl\/cbe-fr\/#website"},"breadcrumb":{"@id":"https:\/\/klantenservice.corendon.nl\/cbe-fr\/category\/logement\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/klantenservice.corendon.nl\/cbe-fr\/category\/logement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/klantenservice.corendon.nl\/cbe-fr\/"},{"@type":"ListItem","position":2,"name":"Logement"}]},{"@type":"WebSite","@id":"https:\/\/klantenservice.corendon.nl\/cbe-fr\/#website","url":"https:\/\/klantenservice.corendon.nl\/cbe-fr\/","name":"Corendon Service Client (FR)","description":"Op deze pagina vindt u vrijwel alle antwoorden op vragen met betrekking tot het boeken van uw vakantie","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/klantenservice.corendon.nl\/cbe-fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/klantenservice.corendon.nl\/cbe-fr\/wp-json\/wp\/v2\/categories\/448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/klantenservice.corendon.nl\/cbe-fr\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/klantenservice.corendon.nl\/cbe-fr\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/klantenservice.corendon.nl\/cbe-fr\/wp-json\/wp\/v2\/posts?categories=448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}